{"id":29312,"date":"2023-03-15T12:53:25","date_gmt":"2023-03-15T11:53:25","guid":{"rendered":"https:\/\/voxea.com\/?p=29312"},"modified":"2024-01-19T16:03:41","modified_gmt":"2024-01-19T15:03:41","slug":"safe-school-multi-level-prevention-concept","status":"publish","type":"post","link":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/","title":{"rendered":"Safe School \u00ae &#8211; Multi-level prevention concept"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"29312\" class=\"elementor elementor-29312\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54d1405a e-flex e-con-boxed e-con e-parent\" data-id=\"54d1405a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11443586 elementor-widget elementor-widget-text-editor\" data-id=\"11443586\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Safe School \u00ae &#8211; Prot\u00e9ger la sant\u00e9 des collaborateurs, des apprenants et des partenaires de VOXEA<\/strong><\/p><p><em>Le label Safe School \u00ae<\/em> est un ensemble de mesures qui a pour objectif de prot\u00e9ger la sant\u00e9 des collaborateurs, des apprenants et des partenaires de centres de formation en luttant contre la propagation du SARS-COV2 et, dans une optique plus large et durable de s\u00e9curit\u00e9 et hygi\u00e8ne au travail, d\u2019agir contre tous agents pathog\u00e8nes afin d\u2019en limiter tr\u00e8s fortement la propagation.<\/p><p><em style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight ); letter-spacing: var( --e-global-typography-text-letter-spacing ); text-align: var(--text-align);\"><strong>Label Safe School \u00ae : Pourquoi ?<\/strong><\/em><\/p><p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight ); letter-spacing: var( --e-global-typography-text-letter-spacing ); text-align: var(--text-align);\">1. De r\u00e9centes recherches ont montr\u00e9 le potentiel du SARS-COV2 de se fixer sur des fibres ou des particules en suspension dans l&rsquo;air libre et sa facult\u00e9 de pouvoir survivre pendant de longues p\u00e9riodes. Une telle voie de transmission par voie a\u00e9rienne &#8211; transmission par a\u00e9rosols, en particulier des a\u00e9rosols fins &#8211; ne peut \u00eatre ignor\u00e9e de m\u00eame que le d\u00e9p\u00f4t de ces a\u00e9rosols sur les surfaces.<\/span><\/p><p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight ); letter-spacing: var( --e-global-typography-text-letter-spacing ); text-align: var(--text-align);\">2. La transmission d\u2019agents pathog\u00e8nes (virus, bact\u00e9ries, germes et moisissures) \u00e0 travers des mat\u00e9riaux tels que les poign\u00e9es de porte, \u00e9crans tactiles, les interrupteurs ou les boutons d\u2019ascenseurs ou de distributeurs est av\u00e9r\u00e9e.<\/span><\/p><p>Les mesures techniques Safe School \u00ae, en plus des mesures organisationnelles et de protection individuelle, ont pour objectif de r\u00e9duire de fa\u00e7on drastique la pr\u00e9sence d\u2019agents pathog\u00e8nes pr\u00e9sents dans l\u2019air ambiant et sur les surfaces et de ce fait d\u2019emp\u00eacher leur propagation.<\/p><p><em><strong>Mesures techniques mises en \u0153uvre :<\/strong><\/em><\/p><p>A) Pose d&rsquo;un film antimicrobien sur les tables, poign\u00e9es de portes, \u00e9crans tactiles et interrupteurs. Ce film \u00e9limine 99% des bact\u00e9ries, telles que Bacillus, Coli, Clostridium, Legionella, Vibrio, Salmonella, Pseudomonas, Staphylococcus, ainsi que les virus, notamment le SARS-COV2.<br \/>B) Installation d&rsquo;appareils de purification d\u2019air UV-C \u00e0 haut d\u00e9bit, totalement innoffensifs pour l&rsquo;\u00eatre humain (sans d\u00e9gagement de chaleur, sans produits chimiques et sans r\u00e9sidus).Ces appareils fonctionnent en continu et \u00e9liminent 99.99% des bact\u00e9ries, telles que Bacillus, Coli, Clostridium, Legionella, Vibrio, Salmonella, Pseudomonas, Staphylococcus, ainsi que les virus, notamment le SARS-CoV2.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da48547 elementor-widget elementor-widget-gallery\" data-id=\"da48547\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;4:3&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns&quot;:4,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/voxea.com\/wp-content\/uploads\/2023\/10\/image00018-1.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"da48547\" data-elementor-lightbox-title=\"Protection anti-bact\u00e9rie sur les tables de l&#039;\u00e9cole\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkzMTMsInVybCI6Imh0dHBzOlwvXC92b3hlYS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEwXC9pbWFnZTAwMDE4LTEuanBlZyIsInNsaWRlc2hvdyI6ImRhNDg1NDcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/voxea.com\/wp-content\/uploads\/2023\/10\/image00018-1.jpeg\" data-width=\"800\" data-height=\"449\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/voxea.com\/wp-content\/uploads\/2023\/10\/img_e7775-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"da48547\" data-elementor-lightbox-title=\"Protection antibact\u00e9rien sur les poign\u00e9es de portes de l&#039;\u00e9cole\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkzMzcsInVybCI6Imh0dHBzOlwvXC92b3hlYS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEwXC9pbWdfZTc3NzUtMS5qcGciLCJzbGlkZXNob3ciOiJkYTQ4NTQ3In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/voxea.com\/wp-content\/uploads\/2023\/10\/img_e7775-1.jpg\" data-width=\"800\" data-height=\"449\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/voxea.com\/wp-content\/uploads\/2023\/10\/img_e7915.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"da48547\" data-elementor-lightbox-title=\"Purificateur d&#039;air pr\u00e9sent dans toutes les salles de l&#039;\u00e9cole\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkzMzgsInVybCI6Imh0dHBzOlwvXC92b3hlYS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEwXC9pbWdfZTc5MTUuanBnIiwic2xpZGVzaG93IjoiZGE0ODU0NyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/voxea.com\/wp-content\/uploads\/2023\/10\/img_e7915.jpg\" data-width=\"800\" data-height=\"449\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/voxea.com\/wp-content\/uploads\/2023\/10\/image00043.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"da48547\" data-elementor-lightbox-title=\"Purificateur antibact\u00e9rien pr\u00e9sent dans la caf\u00e9t\u00e9ria de l&#039;\u00e9cole\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkzMzYsInVybCI6Imh0dHBzOlwvXC92b3hlYS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEwXC9pbWFnZTAwMDQzLmpwZWciLCJzbGlkZXNob3ciOiJkYTQ4NTQ3In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/voxea.com\/wp-content\/uploads\/2023\/10\/image00043.jpeg\" data-width=\"800\" data-height=\"449\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Safe School \u00ae &#8211; Prot\u00e9ger la sant\u00e9 des collaborateurs, des apprenants et des partenaires de VOXEA Le label Safe School \u00ae est un ensemble de mesures qui a pour objectif de prot\u00e9ger la sant\u00e9 des collaborateurs, des apprenants et des partenaires de centres de formation en luttant contre la propagation du SARS-COV2 et, dans une [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":31368,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-29312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formations"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Safe School \u00ae - Multi-level prevention concept - Voxea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Safe School \u00ae - Multi-level prevention concept - Voxea\" \/>\n<meta property=\"og:description\" content=\"Safe School \u00ae &#8211; Prot\u00e9ger la sant\u00e9 des collaborateurs, des apprenants et des partenaires de VOXEA Le label Safe School \u00ae est un ensemble de mesures qui a pour objectif de prot\u00e9ger la sant\u00e9 des collaborateurs, des apprenants et des partenaires de centres de formation en luttant contre la propagation du SARS-COV2 et, dans une [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/\" \/>\n<meta property=\"og:site_name\" content=\"Voxea\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Voxea\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-15T11:53:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-19T15:03:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voxea.com\/wp-content\/uploads\/2023\/03\/safe-school-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathan Mermier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathan Mermier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/\"},\"author\":{\"name\":\"Nathan Mermier\",\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/#\\\/schema\\\/person\\\/c2a4f91549c31df92a7670faaa5269b6\"},\"headline\":\"Safe School \u00ae &#8211; Multi-level prevention concept\",\"datePublished\":\"2023-03-15T11:53:25+00:00\",\"dateModified\":\"2024-01-19T15:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/\"},\"wordCount\":362,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/voxea.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/safe-school-logo.jpg\",\"articleSection\":[\"Formations\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/\",\"url\":\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/\",\"name\":\"Safe School \u00ae - Multi-level prevention concept - Voxea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/voxea.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/safe-school-logo.jpg\",\"datePublished\":\"2023-03-15T11:53:25+00:00\",\"dateModified\":\"2024-01-19T15:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/#primaryimage\",\"url\":\"https:\\\/\\\/voxea.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/safe-school-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/voxea.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/safe-school-logo.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/safe-school-multi-level-prevention-concept\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/voxea.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Safe School \u00ae &#8211; Multi-level prevention concept\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/voxea.com\\\/fr\\\/\",\"name\":\"Voxea\",\"description\":\"Ecole de langue Lausanne\",\"publisher\":{\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voxea.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/#organization\",\"name\":\"Voxea\",\"url\":\"https:\\\/\\\/voxea.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/voxea.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/VOXEA-1973-WEBmedium.png\",\"contentUrl\":\"https:\\\/\\\/voxea.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/VOXEA-1973-WEBmedium.png\",\"width\":500,\"height\":155,\"caption\":\"Voxea\"},\"image\":{\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Voxea\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voxea-sa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voxea.com\\\/fr\\\/#\\\/schema\\\/person\\\/c2a4f91549c31df92a7670faaa5269b6\",\"name\":\"Nathan Mermier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed396c53321237cefb005d4c66c09d7010771d38775c58ba1a477795743d11bb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed396c53321237cefb005d4c66c09d7010771d38775c58ba1a477795743d11bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed396c53321237cefb005d4c66c09d7010771d38775c58ba1a477795743d11bb?s=96&d=mm&r=g\",\"caption\":\"Nathan Mermier\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Safe School \u00ae - Multi-level prevention concept - Voxea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/","og_locale":"fr_FR","og_type":"article","og_title":"Safe School \u00ae - Multi-level prevention concept - Voxea","og_description":"Safe School \u00ae &#8211; Prot\u00e9ger la sant\u00e9 des collaborateurs, des apprenants et des partenaires de VOXEA Le label Safe School \u00ae est un ensemble de mesures qui a pour objectif de prot\u00e9ger la sant\u00e9 des collaborateurs, des apprenants et des partenaires de centres de formation en luttant contre la propagation du SARS-COV2 et, dans une [&hellip;]","og_url":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/","og_site_name":"Voxea","article_publisher":"https:\/\/www.facebook.com\/Voxea","article_published_time":"2023-03-15T11:53:25+00:00","article_modified_time":"2024-01-19T15:03:41+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/voxea.com\/wp-content\/uploads\/2023\/03\/safe-school-logo.jpg","type":"image\/jpeg"}],"author":"Nathan Mermier","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathan Mermier","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/#article","isPartOf":{"@id":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/"},"author":{"name":"Nathan Mermier","@id":"https:\/\/voxea.com\/fr\/#\/schema\/person\/c2a4f91549c31df92a7670faaa5269b6"},"headline":"Safe School \u00ae &#8211; Multi-level prevention concept","datePublished":"2023-03-15T11:53:25+00:00","dateModified":"2024-01-19T15:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/"},"wordCount":362,"commentCount":0,"publisher":{"@id":"https:\/\/voxea.com\/fr\/#organization"},"image":{"@id":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/#primaryimage"},"thumbnailUrl":"https:\/\/voxea.com\/wp-content\/uploads\/2023\/03\/safe-school-logo.jpg","articleSection":["Formations"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/","url":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/","name":"Safe School \u00ae - Multi-level prevention concept - Voxea","isPartOf":{"@id":"https:\/\/voxea.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/#primaryimage"},"image":{"@id":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/#primaryimage"},"thumbnailUrl":"https:\/\/voxea.com\/wp-content\/uploads\/2023\/03\/safe-school-logo.jpg","datePublished":"2023-03-15T11:53:25+00:00","dateModified":"2024-01-19T15:03:41+00:00","breadcrumb":{"@id":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/#primaryimage","url":"https:\/\/voxea.com\/wp-content\/uploads\/2023\/03\/safe-school-logo.jpg","contentUrl":"https:\/\/voxea.com\/wp-content\/uploads\/2023\/03\/safe-school-logo.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/voxea.com\/fr\/safe-school-multi-level-prevention-concept\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/voxea.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Safe School \u00ae &#8211; Multi-level prevention concept"}]},{"@type":"WebSite","@id":"https:\/\/voxea.com\/fr\/#website","url":"https:\/\/voxea.com\/fr\/","name":"Voxea","description":"Ecole de langue Lausanne","publisher":{"@id":"https:\/\/voxea.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voxea.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/voxea.com\/fr\/#organization","name":"Voxea","url":"https:\/\/voxea.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/voxea.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/voxea.com\/wp-content\/uploads\/2025\/07\/VOXEA-1973-WEBmedium.png","contentUrl":"https:\/\/voxea.com\/wp-content\/uploads\/2025\/07\/VOXEA-1973-WEBmedium.png","width":500,"height":155,"caption":"Voxea"},"image":{"@id":"https:\/\/voxea.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Voxea","https:\/\/www.linkedin.com\/company\/voxea-sa\/"]},{"@type":"Person","@id":"https:\/\/voxea.com\/fr\/#\/schema\/person\/c2a4f91549c31df92a7670faaa5269b6","name":"Nathan Mermier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ed396c53321237cefb005d4c66c09d7010771d38775c58ba1a477795743d11bb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed396c53321237cefb005d4c66c09d7010771d38775c58ba1a477795743d11bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed396c53321237cefb005d4c66c09d7010771d38775c58ba1a477795743d11bb?s=96&d=mm&r=g","caption":"Nathan Mermier"}}]}},"_links":{"self":[{"href":"https:\/\/voxea.com\/fr\/wp-json\/wp\/v2\/posts\/29312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voxea.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voxea.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voxea.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/voxea.com\/fr\/wp-json\/wp\/v2\/comments?post=29312"}],"version-history":[{"count":20,"href":"https:\/\/voxea.com\/fr\/wp-json\/wp\/v2\/posts\/29312\/revisions"}],"predecessor-version":[{"id":31372,"href":"https:\/\/voxea.com\/fr\/wp-json\/wp\/v2\/posts\/29312\/revisions\/31372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voxea.com\/fr\/wp-json\/wp\/v2\/media\/31368"}],"wp:attachment":[{"href":"https:\/\/voxea.com\/fr\/wp-json\/wp\/v2\/media?parent=29312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voxea.com\/fr\/wp-json\/wp\/v2\/categories?post=29312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voxea.com\/fr\/wp-json\/wp\/v2\/tags?post=29312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}